{"id":9710,"date":"2025-07-03T08:40:29","date_gmt":"2025-07-03T11:40:29","guid":{"rendered":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/?page_id=9710"},"modified":"2025-12-04T13:30:24","modified_gmt":"2025-12-04T16:30:24","slug":"ana-vera-tourinho-pinheiro-ms","status":"publish","type":"page","link":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/ana-vera-tourinho-pinheiro-ms\/","title":{"rendered":"Ana Vera Tourinho Pinheiro &#8211; MS"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-8353 aligncenter\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/01\/faixaposipa.jpg\" alt=\"\" width=\"950\" height=\"163\" srcset=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/01\/faixaposipa.jpg 950w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/01\/faixaposipa-320x55.jpg 320w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/01\/faixaposipa-768x132.jpg 768w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/01\/faixaposipa-250x43.jpg 250w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/01\/faixaposipa-550x94.jpg 550w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/01\/faixaposipa-800x137.jpg 800w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h2 style=\"text-align: center\"><span data-olk-copy-source=\"MessageBody\">Ana Vera Tourinho Pinheiro<\/span><\/h2>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\">A defesa aconteceu \u00e0s 14:00 do dia 24 de mar\u00e7o de 2025 via Teams, participaram da Banca o Prof. Dr. Denilson Fernandes Peralta, Prof. Dr. Hermeson Oliveira e a Profa. Dra. Ju\u00e7ara Bordin.<\/p>\n<p style=\"text-align: center\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-9711\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2025\/07\/ana-vera-tourinho-pinheiro-ms.png\" alt=\"\" width=\"655\" height=\"374\" srcset=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2025\/07\/ana-vera-tourinho-pinheiro-ms.png 655w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2025\/07\/ana-vera-tourinho-pinheiro-ms-320x183.png 320w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2025\/07\/ana-vera-tourinho-pinheiro-ms-250x143.png 250w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2025\/07\/ana-vera-tourinho-pinheiro-ms-550x314.png 550w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2025\/07\/ana-vera-tourinho-pinheiro-ms-315x180.png 315w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2025\/07\/ana-vera-tourinho-pinheiro-ms-525x300.png 525w\" sizes=\"(max-width: 655px) 100vw, 655px\" \/>O Dom\u00ednio Fitogeogr\u00e1fico do Cerrado possui a terceira maior \u00e1rea e biodiversidade do territ\u00f3rio brasileiro, composto por fitofisionomias divididas em tr\u00eas grandes forma\u00e7\u00f5es: campestre, sav\u00e2nica e florestal, resultando em uma variedade de ambientes e paisagens que propicia uma elevada diversidade flor\u00edstica. Para a conserva\u00e7\u00e3o dessa flora e fauna as Unidades de Conserva\u00e7\u00e3o s\u00e3o de extrema import\u00e2ncia. Dessa forma, o Parque Nacional da Chapada dos Guimar\u00e3es, no estado do Mato Grosso, foi criado com o intuito de proteger e preservar \u00e1reas do Cerrado nativo, sendo registradas, at\u00e9 ent\u00e3o, 659 esp\u00e9cies vegetais vasculares, contudo, n\u00e3o est\u00e3o contabilizadas as esp\u00e9cies da flora avascular. Dito isto, o objetivo desta pesquisa foi o levantamento flor\u00edstico das bri\u00f3fitas do PARNA Chapada dos Guimar\u00e3es, com o intuito de contribuir para o conhecimento e amplia\u00e7\u00e3o da brioflora brasileira, do Cerrado e do estado do Mato Grosso. Por meio da an\u00e1lise de amostras de Herb\u00e1rio e coletas na \u00e1rea do parque. Ao todo foram analisadas 1.405 exsicatas e identificadas 394 esp\u00e9cies de bri\u00f3fitas para PARNA Chapada dos Guimar\u00e3es, dentre elas 31 esp\u00e9cies end\u00eamicas do Brasil e 6 esp\u00e9cies end\u00eamicas do Cerrado. Para o estado do Mato Grosso s\u00e3o relatadas 79 novas ocorr\u00eancias e 73 novas ocorr\u00eancias para o Dom\u00ednio Fitogeogr\u00e1fico do Cerrado, al\u00e9m de uma nova ocorr\u00eancia para o Neotr\u00f3pico, um reencontro para o Brasil de uma esp\u00e9cie n\u00e3o relatada h\u00e1 mais 110 anos, e duas esp\u00e9cies que iremos descrever como novas para a ci\u00eancia. Diante dos resultados obtidos, conclui-se que olevantamento flor\u00edstico apresentado demonstra resultados significativos para a brioflora do Cerrado brasileiro, adicionando um n\u00famero expressivo de esp\u00e9cies para sua biodiversidade e para a biodiversidade do estado do Mato Grosso e dos Parques Nacionais. A notoriedade dos resultados finais deste trabalho demonstra a import\u00e2ncia da realiza\u00e7\u00e3o de levantamentos flor\u00edsticos para que haja uma maior amostragem dos dados da diversidade existente no Brasil e no Neotr\u00f3pico. Juntamente a isso, ressaltamos a import\u00e2ncia dos herb\u00e1rios e suas cole\u00e7\u00f5es bot\u00e2nicas, das rean\u00e1lises das amostras herborizadas e da identifica\u00e7\u00e3o de todas as esp\u00e9cies associadas na exsicata, para que haja assim, o conhecimento mais afinco da biodiversidade brasileira.<\/p>\n<p style=\"text-align: center\">Gostar\u00edamos de agradecer ao Instituto de Pesquisas Ambientais (IPA) e ao Programa de P\u00f3s Gradua\u00e7\u00e3o em Biodiversidade Vegetal e Meio Ambiente, pela infraestrutura e suporte durante o processo de desenvolvimento deste trabalho. \u00c0 CAPES pela bolsa de mestrado concedida e \u00e0 verba PROAP pela ajuda de custo durante as coletas e participa\u00e7\u00e3o de congressos, e aos membros da banca de defesa e qualifica\u00e7\u00e3o.<\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h3 style=\"text-align: center\">Bri\u00f3fitas do Parque Nacional da Chapada dos Guimar\u00e3es, Mato Grosso, Brasil<\/h3>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h4 style=\"text-align: center\"><strong>RESUMO<\/strong><\/h4>\n<p style=\"text-align: justify\">O Dom\u00ednio Fitogeogr\u00e1fico do Cerrado possui a terceira maior \u00e1rea e\u00a0 biodiversidade no territ\u00f3rio brasileiro, vindo atr\u00e1s apenas da Amaz\u00f4nia e da Mata Atl\u00e2ntica. Este det\u00e9m fitofisionomias que est\u00e3o divididas em tr\u00eas grandes forma\u00e7\u00f5es: campestre, sav\u00e2nica e florestal, tamanha variedade de ambientes e paisagens propicia grande diversidade flor\u00edstica. Para a conserva\u00e7\u00e3o da flora e fauna existente foram criadas Unidades de Conserva\u00e7\u00e3o como o Parque Nacional da (PARNA) Chapada dos Guimar\u00e3es, no estado do Mato Grosso, criado em 12 de abril de 1989, com o intuito de proteger e preservar os ecossistemas ali existentes. S\u00e3o registradas para o Parque 659 esp\u00e9cies vegetais vasculares, contudo, n\u00e3o est\u00e3o contabilizadas as esp\u00e9cies da flora avascular, uma vez que estas usualmente n\u00e3o s\u00e3o relatadas em planos de manejo. As bri\u00f3fitas s\u00e3o plantas que n\u00e3o possuem vasos condutores lignificados e dessa forma, apresentam um tamanho reduzido, possuem uma grande import\u00e2ncia ecol\u00f3gica como parte da biomassa, na germina\u00e7\u00e3o de sementes e sucess\u00e3o vegetacional, forma\u00e7\u00e3o dos solos, auxiliando tamb\u00e9m na redu\u00e7\u00e3o da eros\u00e3o e servem como microhabitats para microrganismos diversos. O objetivo desta pesquisa foi o levantamento flor\u00edstico das bri\u00f3fitas do PARNA Chapada dos Guimar\u00e3es, com o intuito de contribuir para o conhecimento e amplia\u00e7\u00e3o da brioflora brasileira, do Cerrado e do estado do Mato Grosso. Por meio da an\u00e1lise de amostras de Herb\u00e1rio e coletas na \u00e1rea do parque. Ao todo foram analisadas 1.405 exsicatas e identificadas 394 esp\u00e9cies de bri\u00f3fitas para PARNA Chapada dos Guimar\u00e3es, dentre elas 31 esp\u00e9cies end\u00eamicas do Brasil e 6 esp\u00e9cies end\u00eamicas do Cerrado. Para o estado do Mato Grosso s\u00e3o relatadas 79 novas ocorr\u00eancias e 73 novas ocorr\u00eancias para o Dom\u00ednio Fitogeogr\u00e1fico do Cerrado, al\u00e9m de uma nova ocorr\u00eancia para o Neotr\u00f3pico, um reencontro para o Brasil de uma esp\u00e9cie n\u00e3o relatada h\u00e1 mais 110 anos, e duas esp\u00e9cies que iremos descrever como novas para a ci\u00eancia. Os dados encontrados salientam a import\u00e2ncia de levantamentos flor\u00edsticos e de \u00e1reas como o PARNA Chapada dos Guimar\u00e3es para a conserva\u00e7\u00e3o da brioflora brasileira.<\/p>\n<p style=\"text-align: justify\"><strong>Palavras-chave<\/strong>:\u00a0 Levantamento flor\u00edstico; Cerrado; Endemismo; Biodiversidade<\/p>\n<p style=\"text-align: center\"><strong>ABSTRACT<\/strong><\/p>\n<p style=\"text-align: justify\">The Phytogeographic Domain of the Cerrado is the third largest in terms of area and biodiversity, following only the Amazon and the Atlantic Forest. It contains various phytophysiognomies divided into three major formations: grassland, savanna, and forest. This wide variety of environments and landscapes promotes great floral diversity. To conserve the existing flora and fauna, Conservation Units were established, such as the Chapada dos Guimar\u00e3es National Park in Mato Grosso, created on April 12, 1989, with the aim of protecting and preserving the ecosystems present there. The park is home to 659 registered vascular plant species; however, non-vascular flora is not counted, as it is not reported in management plans and has few studies associated with it. Bryophytes are plants that lack lignified conductive vessels, resulting in a small size, yet they play a significant ecological role as part of the biomass, in seed germination and vegetation succession, soil formation, and in reducing erosion while providing microhabitats for diverse microorganisms. The objective of this research was to conduct a floristic survey of the bryophytes in Chapada dos Guimar\u00e3es National Park, aiming to contribute to the knowledge and expansion of Brazilian bryoflora, as well as that of the Cerrado and the state of Mato Grosso. Through analysis of collections at the Herbarium-SP and samples from a recent expedition to the park area, totaling 1,405 specimens, 394 bryophyte species were identified for the Chapada dos Guimar\u00e3es National Park, including 31 endemic species of Brazil and 6 endemic species of the Cerrado. For the state of Mato Grosso, 79 new occurrences are reported, along with 73 new occurrences for the Phytogeographic Domain of the Cerrado, one new occurrence for the Neotropics, a rediscovery of a species not reported for over 110 years in Brazil, and two new species not yet known to science. The data emphasize the importance of floristic surveys and areas like the PARNA Chapada dos Guimar\u00e3es for the conservation of Brazilian bryoflora.<\/p>\n<p style=\"text-align: justify\"><strong>Key words: <\/strong>Biodiversity; Bryophytes; Brazilian Savanna; Endemism; Floristic survey<\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2025\/07\/ana_vera_tourinho_pinheiro_ms.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/pdf_grande.gif\" alt=\"pdf_grande\" width=\"60\" height=\"60\" \/><\/a><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2025\/07\/ana_vera_tourinho_pinheiro_ms.pdf\"><strong><span data-olk-copy-source=\"MessageBody\">Ana Vera Tourinho Pinheiro<\/span><\/strong><\/a><br \/>\n<a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2025\/07\/ana_vera_tourinho_pinheiro_ms.pdf\">Bri\u00f3fitas do Parque Nacional da Chapada dos Guimar\u00e3es, Mato Grosso, Brasil<\/a><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><strong>\u00a0<a href=\"www.infraestruturameioambiente.sp.gov.br\/pgibt\/dissertacoesteses\/\">VOLTAR AS DISSERTA\u00c7\u00d5ES E TESES<\/a><\/strong><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"&quot;10&lt;\/p\" \/>\n","protected":false},"excerpt":{"rendered":"<p>Ana Vera Tourinho Pinheiro A defesa aconteceu \u00e0s 14:00 do dia 24 de mar\u00e7o de 2025 via Teams, participaram da Banca o Prof. Dr. Denilson Fernandes Peralta, Prof. Dr. Hermeson Oliveira e a Profa. Dra. Ju\u00e7ara Bordin. O Dom\u00ednio Fitogeogr\u00e1fico do Cerrado possui a terceira maior \u00e1rea e biodiversidade do territ\u00f3rio brasileiro, composto por fitofisionomias [&hellip;]<\/p>\n","protected":false},"author":187,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/9710"}],"collection":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/users\/187"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/comments?post=9710"}],"version-history":[{"count":2,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/9710\/revisions"}],"predecessor-version":[{"id":9752,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/9710\/revisions\/9752"}],"wp:attachment":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/media?parent=9710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}