{"id":8653,"date":"2023-04-12T09:55:51","date_gmt":"2023-04-12T12:55:51","guid":{"rendered":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/?page_id=8653"},"modified":"2023-04-12T10:00:46","modified_gmt":"2023-04-12T13:00:46","slug":"sarah-cristina-de-oliveira-da-paixao-dr","status":"publish","type":"page","link":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/sarah-cristina-de-oliveira-da-paixao-dr\/","title":{"rendered":"Sarah Cristina de Oliveira da Paix\u00e3o &#8211; DR"},"content":{"rendered":"<h2 style=\"text-align: center\"><a href=\"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-3777 size-full\" style=\"border: 0px\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg\" alt=\"faixapos6\" width=\"950\" height=\"163\" srcset=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg 950w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6-768x131.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/a><\/h2>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h2 style=\"text-align: center\">Sarah Cristina de Oliveira da Paix\u00e3o<\/h2>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\">No dia 06 de maio de 2021, por meio de v\u00eddeo chamada pelo aplicativo do googlemeet.com (em decorr\u00eancia da pandemia causada pela COVID-19), a aluna de p\u00f3s-gradua\u00e7\u00e3o em Biodiversidade Vegetal e Meio Ambiente do Instituto de Bot\u00e2nica de S\u00e3o Paulo (IBt), Sarah Cristina Oliveira da Paix\u00e3o, (bolsista FAPESP\/CAPES) defendeu sua tese de doutorado intitulada\u00a0\u201cEstudo morfol\u00f3gico e molecular de esp\u00e9cies do filo <em>Oomycota<\/em> isoladas de cultivo de truta arco-\u00edris (<em>Oncorhynchus mykiss<\/em> Walbaum) em Campos do Jord\u00e3o, estado de S\u00e3o Paulo, Brasil\u201d.<\/p>\n<p style=\"text-align: center\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8658\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr.jpg\" alt=\"\" width=\"1000\" height=\"494\" srcset=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr.jpg 1000w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr-320x158.jpg 320w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr-768x379.jpg 768w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr-250x124.jpg 250w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr-550x272.jpg 550w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr-800x395.jpg 800w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr-364x180.jpg 364w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr-607x300.jpg 607w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p style=\"text-align: center\">A banca examinadora foi composta pela sua orientadora Dra. Carmen Lidia Amorim Pires-Zottarelli (Instituto de Bot\u00e2nica), Dra. Cristiane de Almeida Nascimento (Universidade Federal do Piau\u00ed), Dr.Eduardo Pareira Cabral Gomes (Instituto de Bot\u00e2nica), Dra. Claudia Maris Ferreira Most\u00e9rio (Instituto de Pesca) e Dra. Iracema Helena Schoenlein Crusius (Instituto de Bot\u00e2nica).<\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h3 style=\"text-align: center\">Estudo morfol\u00f3gico e molecular de esp\u00e9cies do filo <em>Oomycota<\/em> isoladas de cultivo de truta arco-\u00edris (<em>Oncorhynchus mykiss Walbaum<\/em>) em Campos do Jord\u00e3o, estado de S\u00e3o Paulo, Brasil<\/h3>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><strong>ABSTRACT<\/strong><\/p>\n<p style=\"text-align: justify\">The intensive cultivation of fish in confined spaces interferes with the ecology of the environment due to trophic interactions and increased organic matter, which can favor the emergence of diseases caused by oomycetes, which are efficient in dispersion in aquatic environments. Saprolegniosis, a disease caused by species of the genus <em>Saprolegnia<\/em>, is the best known of diseases caused by oomycetes, with frequent records in salmonids, in the different stages of fish development. In Brazil, rainbow trout (<em>Oncorhynchus mykiss <\/em>Walbaum) was introduced in the 1940s, and today it is a successful example of fish farming in cold and mountainous regions of the country. However, there is no knowledge about the occurrence of oomycetes in these farming systems in the country, which can affect the quality of the fish and interfere with the production. In view of this, the present study had as main objective to evaluate the richness and the diversity of the representatives of the phylum Oomycota, in two trout farm of Campos do Jord\u00e3o, in the period of one year (August\/November 2016 and March\/June 2017). For this, water samples that supply the cultivation systems were collected; of the breeding tanks, in the different stages of development of the trout, as well as of the water of entrance and exit of the systems. Eggs and dead fish were collected, when present. In laboratory, water samples were treated by the multiple baiting technique, in order to obtain the largest number of specimens. Mycelium of oomycetes apparent in the eggs, as well as obtained by scraping the epidermis of dead fish was inoculated in specific culture media. Through morphological and molecular studies (ITS, LSU and\/or SSU regions of the rDNA), 535 specimens of oomycetes were recorded, from 276 water samples analysed, as well as dead fish and colonized eggs, which belong to the orders Olpidiopsidales s.l., Peronosporales s.l. and Saprolegniales. The order Saprolegniales was the best represented in the study, with genus <em>Achlya<\/em> being the most abundant. The distribution of oomycetes in the studied systems allows us to assume that water is the main means of dispersion of these organisms, which were present in greater abundance in colder periods of the sampling, however, without significant difference in relation to the warmer seasons (p &lt; 0,05). The community structure calculated showed to be diverse the mycota, with 86% similarity between both truticultures. From the specimens obtained in both truticultures, 33 taxa were identified, 23 at specific level, all mentioned for the first time for Campos do Jord\u00e3o. <em>Newbya oblongata<\/em>, <em>Pythiogeton abundans<\/em> and <em>Phytopythium litorale<\/em> are first citations for Brazil, and <em>Aphanomyces brasiliensis<\/em> a new species for science. Oomycetes were registered for the first time in trout farms in the country, expanding the knowledge of these organisms in fish farms in Brazil, with analysis throughout the trout farm system, making it possible to understand the dynamics of these organisms in the system and the identification of potential pathogens.<\/p>\n<p style=\"text-align: justify\"><strong>Keywords<\/strong>: Diversity, oomycetes, trout farm studies<\/p>\n<p style=\"text-align: center\"><strong>RESUMO<\/strong><\/p>\n<p style=\"text-align: justify\">O cultivo intensivo de peixes em espa\u00e7o confinado interfere na ecologia do ambiente devido \u00e0s intera\u00e7\u00f5es tr\u00f3ficas e aumento da mat\u00e9ria org\u00e2nica, o que pode favorecer o surgimento de doen\u00e7as causadas por oomicetos, os quais apresentam efici\u00eancia na dispers\u00e3o em ambientes aqu\u00e1ticos. A saprolegniose, doen\u00e7a causada por esp\u00e9cies do g\u00eanero <em>Saprolegnia<\/em>, \u00e9 a mais conhecida das parasitoses causada por omicetos, com registros frequentes em salmon\u00eddeos, nas diferentes fases de desenvolvimento do peixe. No Brasil, a truta arco-\u00edris (<em>Oncorhynchus mykiss<\/em> Walbaum) foi introduzida na d\u00e9cada de 40, sendo hoje um exemplo de sucesso na cria\u00e7\u00e3o de peixes em regi\u00f5es frias e montanhosas do pa\u00eds. No entanto, n\u00e3o h\u00e1 conhecimento sobre a ocorr\u00eancia de oomicetos nestes sistemas de cultivo no pa\u00eds, os quais podem afetar a qualidade do pescado e interferir na produ\u00e7\u00e3o. Em vista disto, o presente estudo teve como objetivo principal avaliar a riqueza e a diversidade dos representantes do filo Oomycota, em duas truticulturas de Campos do Jord\u00e3o, no per\u00edodo de um ano (agosto\/novembro de 2016 e mar\u00e7o\/junho de 2017). Para isto, foram coletadas amostras da \u00e1gua que abastecem os sistemas de cultivo; dos tanques de cria\u00e7\u00e3o, nas diferentes fases de desenvolvimento da truta, bem como da \u00e1gua de entrada e sa\u00edda dos sistemas. Ovos e peixes mortos foram coletados, quando existentes. Em laborat\u00f3rio, amostras de \u00e1gua foram tratadas pelo m\u00e9todo de iscagem m\u00faltipla, a fim de se obter o maior n\u00famero de esp\u00e9cimes. Mic\u00e9lio de oomicetos aparente nos ovos, bem como obtido pela raspagem da epiderme de peixes mortos coletados, foi inoculado em meios de cultura espec\u00edficos. Por meio de estudos morfol\u00f3gicos e moleculares (regi\u00f5es ITS, LSU e\/ou SSU do rDNA), foram registrados 535 esp\u00e9cimes de oomicetos, de 276 amostras de \u00e1gua analisadas, bem como dos peixes mortos e ovos colonizados, os quais s\u00e3o pertencentes x \u00e0s ordens Olpidiopsidales s.l., Peronosporales s.l. e Saprolegniales. A ordem Saprolegniales foi a melhor representada no estudo, com o g\u00eanero <em>Achlya<\/em> sendo o mais abundante. A distribui\u00e7\u00e3o dos oomicetos nos sistemas estudados permite supor que a \u00e1gua \u00e9 o principal meio de dispers\u00e3o destes organismos, os quais estiveram presentes em maior abund\u00e2ncia em \u00e9pocas mais frias do per\u00edodo de coleta, no entanto, sem diferen\u00e7a significativa com rela\u00e7\u00e3o \u00e0s \u00e9pocas mais quentes (p &lt; 0,05). O c\u00e1lculo da estrutura da comunidade mostrou ser a micota de oomicetos diversa, com 86% de similaridade entre ambas truticulturas. Dos esp\u00e9cimes obtidos nas duas truticulturas, 33 t\u00e1xons foram identificados, com 23 em n\u00edvel espec\u00edfico, todos mencionados pela primeira vez em Campos do Jord\u00e3o. <em>Newbya oblongata<\/em>, <em>Pythiogeton abundans<\/em> e <em>Phytopythium litorale<\/em> s\u00e3o primeiras cita\u00e7\u00f5es para o Brasil, e <em>Aphanomyces brasiliensis <\/em>uma esp\u00e9cie nova para a ci\u00eancia. Pela primeira vez foram registrados oomicetos em truticuluras no pa\u00eds, ampliando o conhecimento destes organismos em pisciculturas no Brasil, com an\u00e1lise em todo o sistema de cultivo da truta, possibilitando compreender a din\u00e2mica destes organismos no sistema e a identifica\u00e7\u00e3o de potenciais pat\u00f3genos.<\/p>\n<p style=\"text-align: justify\"><strong>Palavras-chave: <\/strong>Diversidade, oomicetos, truticultura<\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/pdf_grande.gif\" alt=\"pdf_grande\" width=\"60\" height=\"60\" \/><\/a><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr.pdf\"><strong>Sarah Cristina de Oliveira da Paix\u00e3o<\/strong><\/a><br \/>\n<a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/sites\/242\/2023\/04\/sarah_cristina_de_oliveira_da_paixao-dr.pdf\">Estudo morfol\u00f3gico e molecular de esp\u00e9cies do filo <em>Oomycota<\/em> isoladas de cultivo de truta arco-\u00edris (<em>Oncorhynchus mykiss Walbaum<\/em>) em Campos do Jord\u00e3o, estado de S\u00e3o Paulo, Brasil<\/a><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><strong>\u00a0<a href=\"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/dissertacoesteses\/\" target=\"_blank\" rel=\"noopener noreferrer\">VOLTAR AS DISSERTA\u00c7\u00d5ES E TESES<\/a><\/strong><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n","protected":false},"excerpt":{"rendered":"<p>Sarah Cristina de Oliveira da Paix\u00e3o No dia 06 de maio de 2021, por meio de v\u00eddeo chamada pelo aplicativo do googlemeet.com (em decorr\u00eancia da pandemia causada pela COVID-19), a aluna de p\u00f3s-gradua\u00e7\u00e3o em Biodiversidade Vegetal e Meio Ambiente do Instituto de Bot\u00e2nica de S\u00e3o Paulo (IBt), Sarah Cristina Oliveira da Paix\u00e3o, (bolsista FAPESP\/CAPES) defendeu [&hellip;]<\/p>\n","protected":false},"author":187,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/8653"}],"collection":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/users\/187"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/comments?post=8653"}],"version-history":[{"count":2,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/8653\/revisions"}],"predecessor-version":[{"id":8659,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/8653\/revisions\/8659"}],"wp:attachment":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/media?parent=8653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}