{"id":1407,"date":"2013-09-20T14:17:47","date_gmt":"2013-09-20T17:17:47","guid":{"rendered":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/?page_id=1407"},"modified":"2013-09-20T14:17:47","modified_gmt":"2013-09-20T17:17:47","slug":"2007-silvia-susanne","status":"publish","type":"page","link":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/dissertacoesteses\/2007-silvia-susanne\/","title":{"rendered":"Silvia Susanne Melcher DR"},"content":{"rendered":"<h2 style=\"text-align: center\"><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-3777\" style=\"border: 0px\" alt=\"faixapos6\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg\" width=\"950\" height=\"163\" srcset=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg 950w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6-768x131.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/a><\/h2>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h2 style=\"text-align: center\"><span style=\"color: #003300\">Silvia Susanne Melcher<\/span><\/h2>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h3 style=\"text-align: center\">\u00a0Estudos morfol\u00f3gicos e moleculares de cianobact\u00e9rias potencialmente t\u00f3xicas dos g\u00eaneros <em>Cylindrospermopsis, Aphanizomenon e Raphidiopsis<\/em> (Nostocales)<\/h3>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h4 style=\"text-align: center\"><strong>RESUMO<\/strong><\/h4>\n<p style=\"text-align: justify\">\u00a0As cianobact\u00e9rias heterocitadas dos g\u00eaneros potencialmente t\u00f3xicos\u00a0<em>Cylindrospermopsis\u00a0<\/em>(Woloszynska) Seenayya &amp; Subba Raju ,\u00a0<em>Aphanizomenon<\/em>\u00a0Morren ex Bornet et Flahault e\u00a0<em>Raphidiopsis<\/em>\u00a0Fritsch et Rich possuem ampla plasticidade fenot\u00edpica, sendo frequentemente confundidas em material da natureza. Em estudos com material cultivado, s\u00e3o pobremente descritas do ponto de vista morfol\u00f3gico.\u00a0 As rela\u00e7\u00f5es filogen\u00e9ticas existentes entre estas cianobact\u00e9rias potencialmente t\u00f3xicas tamb\u00e9m s\u00e3o pouco conhecidas, a despeito de sua semelhan\u00e7a morfol\u00f3gica. As esp\u00e9cies de\u00a0<em>Cylindrospermopsis<\/em>,\u00a0<em>Aphanizomenon<\/em>\u00a0e<em>Raphidiopsis<\/em>\u00a0s\u00e3o conhecidas em todo mundo como produtoras de neurotoxinas. No Brasil, grande parte das refer\u00eancias a cianotoxinas \u00e9 relativa a flora\u00e7\u00f5es destes g\u00eaneros, mas poucas esp\u00e9cies ou linhagens foram testadas quanto \u00e0 produ\u00e7\u00e3o de toxinas. Assim, o objetivo do presente trabalho foi descrever dez linhagens brasileiras pertencentes aos tr\u00eas g\u00eaneros, a fim de compar\u00e1-las segundo crit\u00e9rios morfom\u00e9tricos e estabelecer as rela\u00e7\u00f5es filogen\u00e9ticas existentes entre elas. Alem disso, foi feita an\u00e1lise da produ\u00e7\u00e3o de toxinas das dez linhagens brasileiras estudadas. Todas as linhagens apresentaram ampla varia\u00e7\u00e3o morfol\u00f3gica. Das vari\u00e1veis analisadas, somente a raz\u00e3o comprimento\/di\u00e2metro da c\u00e9lula apical mostrou-se adequada para separar o g\u00eanero\u00a0<em>Aphanizomenon\u00a0<\/em>do complexo\u00a0<em>Cylindrospermopsis\/Raphidiopsis.<\/em>\u00a0Todas as demais vari\u00e1veis analisadas mostraram-se inadequadas para a delimita\u00e7\u00e3o dos g\u00eaneros por apresentaram descontinuidade em n\u00edvel sub-espec\u00edfico. Em duas das linhagens de\u00a0<em>Aphanizomenon<\/em>, as caracter\u00edsticas diacr\u00edticas do g\u00eanero n\u00e3o se mantiveram est\u00e1veis quando da redu\u00e7\u00e3o da disponibilidade de nitrog\u00eanio no meio de cultura, apontando para sua depend\u00eancia de fatores ambientais. As linhagens pertencentes aos g\u00eaneros\u00a0<em>Cylindrospermopsis<\/em>\u00a0e\u00a0<em>Raphidiopsis\u00a0<\/em>constitu\u00edram, nas \u00e1rvores de\u00a0<em>neighbor<\/em>\u00a0<em>joining<\/em>\u00a0e m\u00e1xima parcim\u00f4nia, clado monofil\u00e9tico entre si e com seq\u00fc\u00eancias de\u00a0<em>Cylindrospermopsis\u00a0<\/em>dispon\u00edveis no\u00a0<em>GenBank<\/em>, ao passo que duas linhagens de\u00a0<em>Aphanizomenon\u00a0<\/em>se agruparam com seq\u00fc\u00eancias de\u00a0<em>Aphanizomenon\u00a0<\/em>e\u00a0<em>Anabaena\u00a0<\/em>dispon\u00edveis no\u00a0<em>GenBank<\/em><em>\u00a0<\/em>e duas constitu\u00edram clado de posi\u00e7\u00e3o intermedi\u00e1ria entre o grupo\u00a0<em>Cylindrospermopsis\/Raphidiopsis<\/em>\u00a0e o grupo<em>Aphanizomenon\/Anabaena.<\/em>\u00a0A identidade das duas seq\u00fc\u00eancias de RNAr 16S de\u00a0<em>Raphidiopsis\u00a0<\/em>estudadasfoi superior a 98% com todas as seq\u00fc\u00eancias de\u00a0<em>Cylindrospermopsis<\/em>\u00a0analisadas, apontando para a fragilidade do g\u00eanero. Duas linhagens de<em>Cylindrospermopsis<\/em>\u00a0e uma das duas linhagens de\u00a0<em>Raphidiopsis\u00a0<\/em>testadasrevelaram-se neurot\u00f3xicas. Das linhagens de<em>Aphanizomenon\u00a0<\/em>testadas, nenhuma se mostrou t\u00f3xica.<\/p>\n<p><strong>Palavras-Chave:<\/strong>\u00a0Nostocales, cultura, plasticidade fenot\u00edpica, rela\u00e7\u00f5es filogen\u00e9ticas, produ\u00e7\u00e3o de toxinas.<\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/pdf_grande.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-2313\" style=\"border: 0px\" alt=\"pdf_grande\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/pdf_grande.gif\" width=\"60\" height=\"60\" \/><\/a><br \/>\n<a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/Silvia_Susanne_Melcher_DR.pdf\" target=\"_blank\">Silvia Susanne Melcher Estudos morfol\u00f3gicos e moleculares de cianobact\u00e9rias potencialmente t\u00f3xicas dos g\u00eaneros<br \/>\n<em>Cylindrospermopsis, Aphanizomenon\u00a0<\/em>e<em>\u00a0Raphidiopsis <\/em>(Nostocales)<\/a><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><strong>\u00a0<a href=\"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/dissertacoesteses\/\">VOLTAR AS DISSERTA\u00c7\u00d5ES E TESES<\/a><\/strong><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n","protected":false},"excerpt":{"rendered":"<p>Silvia Susanne Melcher \u00a0Estudos morfol\u00f3gicos e moleculares de cianobact\u00e9rias potencialmente t\u00f3xicas dos g\u00eaneros Cylindrospermopsis, Aphanizomenon e Raphidiopsis (Nostocales) RESUMO \u00a0As cianobact\u00e9rias heterocitadas dos g\u00eaneros potencialmente t\u00f3xicos\u00a0Cylindrospermopsis\u00a0(Woloszynska) Seenayya &amp; Subba Raju ,\u00a0Aphanizomenon\u00a0Morren ex Bornet et Flahault e\u00a0Raphidiopsis\u00a0Fritsch et Rich possuem ampla plasticidade fenot\u00edpica, sendo frequentemente confundidas em material da natureza. Em estudos com material cultivado, s\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":249,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"fullpage.php","meta":[],"_links":{"self":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/1407"}],"collection":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/comments?post=1407"}],"version-history":[{"count":0,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/1407\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/249"}],"wp:attachment":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/media?parent=1407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}