{"id":1039,"date":"2013-09-18T14:53:48","date_gmt":"2013-09-18T17:53:48","guid":{"rendered":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/?page_id=1039"},"modified":"2013-09-18T14:53:48","modified_gmt":"2013-09-18T17:53:48","slug":"2011-murilo-rondoni-tanus","status":"publish","type":"page","link":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/dissertacoesteses\/2011-murilo-rondoni-tanus\/","title":{"rendered":"Murilo Rondoni Tanus MS"},"content":{"rendered":"<h2 style=\"text-align: center\"><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-3777\" style=\"border: 0px\" alt=\"faixapos6\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg\" width=\"950\" height=\"163\" srcset=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg 950w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6-768x131.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/a><\/h2>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h2 style=\"text-align: center\">Murilo Rondoni Tanus<\/h2>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\">No dia 28 de julho de 2011 Murilo Rondoni Tanus, bacharel em Biologia, defendeu sua disserta\u00e7\u00e3o de Mestrado.<br \/>\nA defesa ocorreu \u00e0s 9:00h tendo como membros da banca a Dra. Flaviana Maluf de Souza do Instituto Florestal do Estado de S\u00e3o Paulo, a Dra. Simey Thury Vieira Fisch do Departamento de Bioci\u00eancias da Universidade de Taubat\u00e9 e o orientador Dr. Eduardo Pereira Cabral Gomes do Instituto de Bot\u00e2nica.<br \/>\nA disserta\u00e7\u00e3o foi aprovada pelos membros da banca.<\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h3 style=\"text-align: center\">Flor\u00edstica e estrutura da comunidade arb\u00f3reo-arbustiva e o efeito de borda em trecho de Mata Atl\u00e2ntica<br \/>\nno Parque Estadual das Fontes do Ipiranga, S\u00e3o Paulo, SP<\/h3>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h4 style=\"text-align: center\"><strong>RESUMO<\/strong><\/h4>\n<p style=\"text-align: justify\">A fragmenta\u00e7\u00e3o acelerada provoca a forma\u00e7\u00e3o de bordas e estas influenciam diretamente a din\u00e2mica das comunidades vegetais, sua composi\u00e7\u00e3o de esp\u00e9cies e as caracter\u00edsticas da paisagem de fragmentos florestais. Este trabalho foi realizado em um trecho de Mata Atl\u00e2ntica de 5 ha localizado no Parque Estadual das Fontes do Ipiranga (PEFI). Todos os indiv\u00edduos com altura \u2265 2,5 m foram amostrados em 30 parcelas circulares de 50 m2 (3,99 m de raio) a 5, 15 e 45 m da borda. Distribu\u00edram-se aleatoriamente 10 parcelas por dist\u00e2ncia. Foi testada a hip\u00f3tese de que o efeito de borda \u00e9 determinante na varia\u00e7\u00e3o da estrutura, composi\u00e7\u00e3o do componente lenhoso e no car\u00e1ter sucessional das esp\u00e9cies da Mata Atl\u00e2ntica do planalto paulista do PEFI. Tamb\u00e9m averiguamos se os efeitos de borda s\u00e3o menores do que aqueles verificados em \u00e1reas de florestas cont\u00ednuas e se a estrutura e riqueza da \u00e1rea de estudo se assemelha a outras \u00e1reas do PEFI e a outros trechos de florestas de regi\u00f5es pr\u00f3ximas. Os resultados confirmaram uma diferen\u00e7a significativa da percentagem de esp\u00e9cies pioneiras, densidade absoluta e altura entre a borda e o interior do fragmento. As curvas de rarefa\u00e7\u00e3o indicaram que a riqueza de esp\u00e9cies \u00e9 semelhante entre a \u00e1rea de borda e interior. Myrtaceae e Lauraceae com 12 esp\u00e9cies e Rubiaceae com 11 foram as fam\u00edlias mais ricas em esp\u00e9cies, enquanto, Lauraceae, Rubiaceae e Euphorbiaceae, respectivamente com 112, 80 e 72 indiv\u00edduos as fam\u00edlias mais abundantes. O trabalho mostrou que mesmo em pequenos fragmentos, quando protegidos, com \u00e1reas diminutas e influenciadas pelo efeito de borda, a riqueza de esp\u00e9cies arb\u00f3reas, quando comparadas com trechos florestais na regi\u00e3o do Alto da Bacia do Tiet\u00ea pode ser grande. O efeito de borda n\u00e3o atua de forma homog\u00eanea por todo o fragmento, evidenciando algumas diferen\u00e7as significativas entre o ambiente de borda e o interior de mata, para algumas vari\u00e1veis. Apesar da riqueza semelhante entre as \u00e1reas do PEFI, a composi\u00e7\u00e3o e abund\u00e2ncia de esp\u00e9cies apresentaram diferen\u00e7as entre trechos pr\u00f3ximos de mata, visualizadas na An\u00e1lise de Coordenadas Principais.<\/p>\n<p style=\"text-align: justify\">\u00a0Palavras-chave: Fragmenta\u00e7\u00e3o, gradiente, sucess\u00e3o<\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/pdf_grande.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-2313\" style=\"border: 0px\" alt=\"pdf_grande\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/pdf_grande.gif\" width=\"60\" height=\"60\" \/><\/a><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/Murilo_Rondoni_Tanus_MS.pdf\" target=\"_blank\">Murilo Rondoni Tanus<br \/>\nFlor\u00edstica e estrutura da comunidade arb\u00f3reo-arbustiva e o efeito de borda em trecho de<br \/>\nMata Atl\u00e2ntica no Parque Estadual das Fontes do Ipiranga, S\u00e3o Paulo, SP<\/a><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><strong>\u00a0<a href=\"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/dissertacoesteses\/\">VOLTAR AS DISSERTA\u00c7\u00d5ES E TESES<\/a><\/strong><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n","protected":false},"excerpt":{"rendered":"<p>Murilo Rondoni Tanus No dia 28 de julho de 2011 Murilo Rondoni Tanus, bacharel em Biologia, defendeu sua disserta\u00e7\u00e3o de Mestrado. A defesa ocorreu \u00e0s 9:00h tendo como membros da banca a Dra. Flaviana Maluf de Souza do Instituto Florestal do Estado de S\u00e3o Paulo, a Dra. Simey Thury Vieira Fisch do Departamento de Bioci\u00eancias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":249,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"fullpage.php","meta":[],"_links":{"self":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/1039"}],"collection":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/comments?post=1039"}],"version-history":[{"count":0,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/1039\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/249"}],"wp:attachment":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/media?parent=1039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}