{"id":1012,"date":"2013-09-18T13:18:21","date_gmt":"2013-09-18T16:18:21","guid":{"rendered":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/?page_id=1012"},"modified":"2013-09-18T13:18:21","modified_gmt":"2013-09-18T16:18:21","slug":"2011-juliana-kuroiva-zerlin","status":"publish","type":"page","link":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/dissertacoesteses\/2011-juliana-kuroiva-zerlin\/","title":{"rendered":"Juliana Kuroiva Zerlin MS"},"content":{"rendered":"<h2 style=\"text-align: center\"><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-3777\" style=\"border: 0px\" alt=\"faixapos6\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg\" width=\"950\" height=\"163\" srcset=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6.jpg 950w, https:\/\/smastr16.blob.core.windows.net\/pgibt\/2015\/02\/faixapos6-768x131.jpg 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/a><\/h2>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h2 style=\"text-align: center\">Juliana Kuroiva Zerlin<\/h2>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\">No dia 25 de fevereiro de 2011, a bi\u00f3loga Juliana Kuroiva Zerlin (bolsista FAPESP), aluna do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Biodiversidade Vegetal e Meio Ambiente do Instituto de Bot\u00e2nica de S\u00e3o Paulo (IBt), defendeu sua disserta\u00e7\u00e3o de mestrado intitulada:<br \/>\n\u201cInflu\u00eancia do \u00f3xido n\u00edtrico nos processos de embebi\u00e7\u00e3o e mobiliza\u00e7\u00e3o de reservas durante a germina\u00e7\u00e3o\u00a0e o desenvolvimento inicial<br \/>\nde pl\u00e2ntulas de\u00a0<em>Sesbania virgata\u00a0<\/em>(Cav.) Pers. e\u00a0<em>Hymenaea courbaril<\/em>\u00a0L.\u201d.<br \/>\nA banca examinadora foi presidida pela sua orientadora Dra. Mar\u00edlia Gaspar (IBt) e contou com a participa\u00e7\u00e3o como convidadas externas da\u00a0Dra. Ione Salgado (UNICAMP) e da Dra. Patr\u00edcia Pinho Tonini (Centro Universit\u00e1rio S\u00e3o Camilo).<\/p>\n<div id=\"attachment_1013\" style=\"width: 384px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/juliana_zerlin1.jpg\"><img aria-describedby=\"caption-attachment-1013\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-1013\" alt=\"Dra. Ione Salgado (UNICAMP), Dra. Mar\u00edlia Gaspar (IBt), MSc. Juliana Kuroiva Zerlin e Dra. Patr\u00edcia Pinho Tonini (Centro Universit\u00e1rio S\u00e3o Camilo).\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/juliana_zerlin1.jpg\" width=\"374\" height=\"239\" \/><\/a><p id=\"caption-attachment-1013\" class=\"wp-caption-text\">Dra. Ione Salgado (UNICAMP), Dra. Mar\u00edlia Gaspar (IBt), MSc. Juliana Kuroiva Zerlin e<br \/>Dra. Patr\u00edcia Pinho Tonini (Centro Universit\u00e1rio S\u00e3o Camilo).<\/p><\/div>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h3 style=\"text-align: center\">Influ\u00eancia do \u00f3xido n\u00edtrico nos processos de embebi\u00e7\u00e3o e mobiliza\u00e7\u00e3o de reservas durante a germina\u00e7\u00e3o e o desenvolvimento inicial de pl\u00e2ntulas de <em>Sesbania virgata<\/em> (Cav.) Pers. e <em>Hymenaea courbaril<\/em> L.<\/h3>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<h4 style=\"text-align: center\"><strong>RESUMO<\/strong><\/h4>\n<p style=\"text-align: justify\">O \u00f3xido n\u00edtrico (NO) \u00e9 um radical livre gasoso que se difunde rapidamente atrav\u00e9s das membranas e tem sido reportado como uma potente mol\u00e9cula de sinaliza\u00e7\u00e3o em plantas e animais. Sua aplica\u00e7\u00e3o ex\u00f3gena estimula a germina\u00e7\u00e3o e a quebra de dorm\u00eancia em sementes, mas os mecanismos pelos quais o \u00f3xido n\u00edtrico estimula estes processos ainda s\u00e3o desconhecidos. O NO aumenta a atividade de enzimas hidrol\u00edticas que atuam na quebra do amido durante a germina\u00e7\u00e3o de algumas esp\u00e9cies e estimula o crescimento e a s\u00edntese de celulose em ra\u00edzes. No entanto, at\u00e9 o presente momento, n\u00e3o existem informa\u00e7\u00f5es acerca do papel deste modulador no processo de degrada\u00e7\u00e3o de reservas e crescimento em sementes acumuladoras de polissacar\u00eddeos de reserva de parede celular. Nos biomas Cerrado e Mata Atl\u00e2ntica, as esp\u00e9cies apresentam estrat\u00e9gias de adapta\u00e7\u00e3o diversas e muitas delas envolvem os carboidratos de reserva. Diversas leguminosas arb\u00f3reas, entre elas\u00a0<em>Sesbania virgata<\/em>\u00a0(Faboideae) e\u00a0<em>Hymenaea courbaril<\/em>\u00a0(Caesalpinoideae), apresentam altas propor\u00e7\u00f5es de carboidratos de parede celular como reserva em suas sementes, que s\u00e3o mobilizados ap\u00f3s a germina\u00e7\u00e3o, fornecendo carbono e energia para o crescimento inicial da pl\u00e2ntula. Desta forma, este trabalho objetivou compreender o papel do NO nos processos de germina\u00e7\u00e3o e desenvolvimento inicial em duas esp\u00e9cies de leguminosas,\u00a0<em>S. virgata\u00a0<\/em>e\u00a0<em>H. courbaril<\/em>, cujas sementes acumulam galactomanano e xiloglucano como polissacar\u00eddeos de reserva de parede celular. Para avaliar o efeito do NO, as sementes de\u00a0<em>S. virgata\u00a0<\/em>e\u00a0<em>H. courbaril\u00a0<\/em>foram embebidas em \u00e1gua destilada e em solu\u00e7\u00f5es doadoras e sequestradoras de NO tendo, sido analisados par\u00e2metros fisiol\u00f3gicos de germina\u00e7\u00e3o e par\u00e2metros bioqu\u00edmicos relacionados \u00e0 degrada\u00e7\u00e3o das reservas e crescimento. Os doadores de NO n\u00e3o tiveram influ\u00eancia sobre a taxa de germina\u00e7\u00e3o, por\u00e9m o NO interferiu no metabolismo de reserva das sementes de\u00a0<em>S. virgata.<\/em>\u00a0Os n\u00edveis mais baixos de rafinose indicam que o NO acelerou a degrada\u00e7\u00e3o desse oligossacar\u00eddeo presente no endosperma, resultando no aumento de galactose e sacarose direcionadas para o crescimento radicular. O aumento da atividade espec\u00edfica da enzima alfa-galactosidase, que inicia o processo de degrada\u00e7\u00e3o do galactomanano, com conseq\u00fcente aumento do teor de galactose e manose, sugere que o NO estimulou a degrada\u00e7\u00e3o desta reserva p\u00f3s-germinativa. A diminui\u00e7\u00e3o no teor de prote\u00ednas, associada ao aumento de glutamina e asparagina, sugere o efeito estimulador do NO na degrada\u00e7\u00e3o de prote\u00ednas de reserva. A a\u00e7\u00e3o do NO sobre as reservas da semente parece estar indiretamente relacionado ao teor de ABA. A an\u00e1lise do perfil metab\u00f3lico do endosperma e das ra\u00edzes mostrou que o metabolismo das sementes de\u00a0<em>S. virgata<\/em>\u00a0como um todo foi afetado pelo NO, tendo em vista as varia\u00e7\u00f5es nos teores de prote\u00ednas, amino\u00e1cidos, a\u00e7\u00facares e \u00e1cidos org\u00e2nicos. O NO n\u00e3o promoveu est\u00edmulo da germina\u00e7\u00e3o de sementes de\u00a0<em>H. courbaril<\/em>, mas induziu um aumento no tamanho das rad\u00edculas. As maiores taxas de crescimento n\u00e3o puderam ser correlacionadas a modifica\u00e7\u00f5es do perfil metab\u00f3lico das ra\u00edzes e a um aumento da s\u00edntese de celulose. Por outro lado, o NO estimulou a germina\u00e7\u00e3o de jatob\u00e1 em lote de sementes com menor vigor, sugerindo sua utiliza\u00e7\u00e3o como ferramenta importante em tecnologia de sementes,\u00a0visando acelerar o processo de germina\u00e7\u00e3o e favorecer o desenvolvimento das pl\u00e2ntulas.<\/p>\n<p style=\"text-align: justify\"><strong>Palavras-chave:<\/strong>\u00a0germina\u00e7\u00e3o, \u00f3xido n\u00edtrico, degrada\u00e7\u00e3o de reservas, crescimento radicular.<\/p>\n<div id=\"attachment_1014\" style=\"width: 326px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/juliana_zerlin2.jpg\"><img aria-describedby=\"caption-attachment-1014\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-1014\" alt=\"Sementes estudadas: (A) Sesbania virgata, (B) Hymenaea courbaril. \" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/juliana_zerlin2.jpg\" width=\"316\" height=\"150\" \/><\/a><p id=\"caption-attachment-1014\" class=\"wp-caption-text\">Sementes estudadas: (A) <em>Sesbania virgata,<\/em> (B) <em>Hymenaea courbaril.<\/em><\/p><\/div>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/pdf_grande.gif\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-2313\" style=\"border: 0px\" alt=\"pdf_grande\" src=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/pdf_grande.gif\" width=\"60\" height=\"60\" \/><\/a><a href=\"https:\/\/smastr16.blob.core.windows.net\/pgibt\/2013\/09\/Juliana_Kuroiva_Zerlin_MS.pdf\" target=\"_blank\">Juliana Kuroiva Zerlin<br \/>\nInflu\u00eancia do \u00f3xido n\u00edtrico nos processos de embebi\u00e7\u00e3o e mobiliza\u00e7\u00e3o de reservas durante a germina\u00e7\u00e3o e o desenvolvimento inicial<br \/>\nde pl\u00e2ntulas de\u00a0<em>Sesbania virgata<\/em>\u00a0(Cav.) Pers. e\u00a0<em>Hymenaea courbaril<\/em>\u00a0L.<\/a><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n<p style=\"text-align: center\"><strong>\u00a0<a href=\"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/dissertacoesteses\/\">VOLTAR AS DISSERTA\u00c7\u00d5ES E TESES<\/a><\/strong><\/p>\n<hr align=\"center\" noshade=\"noshade\" size=\"1\" width=\"100%\" \/>\n","protected":false},"excerpt":{"rendered":"<p>Juliana Kuroiva Zerlin No dia 25 de fevereiro de 2011, a bi\u00f3loga Juliana Kuroiva Zerlin (bolsista FAPESP), aluna do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Biodiversidade Vegetal e Meio Ambiente do Instituto de Bot\u00e2nica de S\u00e3o Paulo (IBt), defendeu sua disserta\u00e7\u00e3o de mestrado intitulada: \u201cInflu\u00eancia do \u00f3xido n\u00edtrico nos processos de embebi\u00e7\u00e3o e mobiliza\u00e7\u00e3o de reservas durante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":249,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"fullpage.php","meta":[],"_links":{"self":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/1012"}],"collection":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/comments?post=1012"}],"version-history":[{"count":0,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/1012\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/pages\/249"}],"wp:attachment":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/pgibt\/wp-json\/wp\/v2\/media?parent=1012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}