{"id":7599,"date":"2024-12-03T11:56:00","date_gmt":"2024-12-03T14:56:00","guid":{"rendered":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/?p=7599"},"modified":"2024-12-03T12:01:59","modified_gmt":"2024-12-03T15:01:59","slug":"programa-de-educacao-ambiental-do-ipa-incentiva-dialogo-entre-conservacao-ambiental-e-valorizacao-das-culturas-quilombola-e-caicara","status":"publish","type":"post","link":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/2024\/12\/programa-de-educacao-ambiental-do-ipa-incentiva-dialogo-entre-conservacao-ambiental-e-valorizacao-das-culturas-quilombola-e-caicara\/","title":{"rendered":"Programa de Educa\u00e7\u00e3o Ambiental do IPA incentiva di\u00e1logo entre conserva\u00e7\u00e3o ambiental e valoriza\u00e7\u00e3o das culturas quilombola e cai\u00e7ara"},"content":{"rendered":"<p>Entre os dias 15 e 17 de novembro, representantes de <a href=\"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/2024\/11\/educatrilha-na-escola-programa-de-educacao-ambiental-do-ipa-beneficiou-mais-de-9-mil-pessoas-somente-em-2024\/\">escolas premiadas na 5\u00aa edi\u00e7\u00e3o do programa &#8220;EducaTrilha na Escola&#8221;<\/a> visitaram o N\u00facleo Picinguaba do Parque Estadual da Serra do Mar (PESM), no munic\u00edpio de Ubatuba\/SP.<\/p>\n<p>O programa de Educa\u00e7\u00e3o Ambiental promovido pelo Instituto de Pesquisas Ambientais (IPA), junto a parceiros, consiste em um processo de forma\u00e7\u00e3o junto a professores e um concurso anual de projetos educativos nas escolas da regi\u00e3o de Piracicaba\/SP. Entre seus objetivos est\u00e1 o de envolver diversos atores sociais na constru\u00e7\u00e3o participativa de um programa de educa\u00e7\u00e3o ambiental, cultural, inclusiva de promo\u00e7\u00e3o da sa\u00fade e bem-estar no enfrentamento das mudan\u00e7as socioambientais globais, de forma a abranger escolas, \u00e1reas protegidas e outros espa\u00e7os educativos.<\/p>\n<p>&#8220;O N\u00facleo Picinguaba \u00e9 o \u00fanico do PESM que abrange ecossistemas de floresta, restinga, mangue e praia. Assim, a programa\u00e7\u00e3o da viagem foi elaborada junto com a equipe gestora da unidade de conserva\u00e7\u00e3o, buscando propiciar uma diversidade de experi\u00eancias em todos esses ecossistemas&#8221;, comenta Maria Lu\u00edsa Palmieri, especialista ambiental do IPA e coordenadora do programa. As atividades inclu\u00edram trilhas nos diferentes ecossistemas, viv\u00eancias na praia e visita ao Quilombo da Fazenda &#8211; Casa da Farinha, com di\u00e1logos sobre a hist\u00f3ria e cultura locais. &#8220;Se buscou valorizar as comunidades tradicionais que vivem no N\u00facleo, incentivando o di\u00e1logo sobre as rela\u00e7\u00f5es entre conserva\u00e7\u00e3o ambiental e valoriza\u00e7\u00e3o das culturas quilombola e cai\u00e7ara&#8221;, complementa.<\/p>\n<p>Participaram da viagem 18 representantes das seis escolas premiadas pelo programa em 2024 e cinco representantes das institui\u00e7\u00f5es organizadoras. A edi\u00e7\u00e3o de 2024 do EducaTrilha na Escola foi realizada pelo IPA em parceria com a <a href=\"https:\/\/fflorestal.sp.gov.br\/\">Funda\u00e7\u00e3o Florestal (FF)<\/a>, a <a href=\"https:\/\/piracicaba.sp.gov.br\/\">Prefeitura de Piracicaba<\/a>, o Projeto Corredor Caipira e a E<a href=\"https:\/\/www.esalq.usp.br\/\">scola Superior de Agricultura \u201cLuiz de Queiroz\u201d da Universidade de S\u00e3o Paulo (Esalq\/USP)<\/a>. O programa \u00e9 patrocinado pela CJ do Brasil e pela OJI Pap\u00e9is.<\/p>\n<div class=\"wc-gallery\"><div class='wcflexslider-container wc-gallery-bottomspace-default wc-gallery-clear'><div id='gallery-1' class='gallery wc-gallery-captions-onhover gallery-link-file wcflexslider wcsliderauto' data-gutter-width='5' data-columns='1' data-hide-controls='false'><ul class='slides'>\n\t\t\t\t<li class='gallery-item gallery-item-position-1 gallery-item-attachment-7602 wcflex-slide-item'>\n\t\t\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t\t\t<a href=\"https:\/\/smastr16.blob.core.windows.net\/2001\/sites\/261\/2024\/12\/atividade-contou-com-a-participacao-de-educadores-divulgacao-educatrilha-na-escola.jpeg\" target=\"_self\"><img src='https:\/\/smastr16.blob.core.windows.net\/2001\/sites\/261\/2024\/12\/atividade-contou-com-a-participacao-de-educadores-divulgacao-educatrilha-na-escola-550x413.jpeg' width='550' height='413' alt='' \/><\/a>\n\t\t\t\t\t<\/div><\/li>\n\t\t\t\t<li class='gallery-item gallery-item-position-2 gallery-item-attachment-7604 wcflex-slide-item'>\n\t\t\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t\t\t<a href=\"https:\/\/smastr16.blob.core.windows.net\/2001\/sites\/261\/2024\/12\/viagem-abordou-conservacao-ambiental-divulgacao-educatrilha-na-escola.jpeg\" target=\"_self\"><img src='https:\/\/smastr16.blob.core.windows.net\/2001\/sites\/261\/2024\/12\/viagem-abordou-conservacao-ambiental-divulgacao-educatrilha-na-escola-550x413.jpeg' width='550' height='413' alt='' \/><\/a>\n\t\t\t\t\t<\/div><\/li><\/ul><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias 15 e 17 de novembro, representantes de escolas premiadas na 5\u00aa edi\u00e7\u00e3o do programa &#8220;EducaTrilha na Escola&#8221; visitaram o N\u00facleo Picinguaba do Parque Estadual da Serra do [&hellip;]<\/p>\n","protected":false},"author":197,"featured_media":7603,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,5],"tags":[500,499,37,498,180,497,501],"_links":{"self":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/posts\/7599"}],"collection":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/users\/197"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/comments?post=7599"}],"version-history":[{"count":5,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/posts\/7599\/revisions"}],"predecessor-version":[{"id":7608,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/posts\/7599\/revisions\/7608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/media\/7603"}],"wp:attachment":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/media?parent=7599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/categories?post=7599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/ipa\/wp-json\/wp\/v2\/tags?post=7599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}