{"id":29075,"date":"2017-04-19T10:35:57","date_gmt":"2017-04-19T13:35:57","guid":{"rendered":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/?p=29075"},"modified":"2023-07-24T02:39:52","modified_gmt":"2023-07-24T05:39:52","slug":"pregao-eletronico-no-012017-cbrn","status":"publish","type":"post","link":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/2017\/04\/pregao-eletronico-no-012017-cbrn\/","title":{"rendered":"Preg\u00e3o Eletr\u00f4nico N\u00ba 01\/2017 &#8211; CBRN"},"content":{"rendered":"<p><strong>Processo:<\/strong> 1.953\/2017<\/p>\n<p><strong>Pre\u00e2mbulo:<\/strong> Processo de contrata\u00e7\u00e3o de servi\u00e7os comuns \u2013 Contrata\u00e7\u00e3o de empresa para presta\u00e7\u00e3o de servi\u00e7os de limpeza, asseio e conserva\u00e7\u00e3o predial para a URAT de S\u00e3o Carlos.<\/p>\n<p><strong>Data e hora da abertura da sess\u00e3o p\u00fablica:<\/strong> 05\/05\/2017 \u00e0s 09h00.<\/p>\n<p>Acha-se aberta na Coordenadoria de Fiscaliza\u00e7\u00e3o Ambiental, da Secretaria do Meio Ambiente, a licita\u00e7\u00e3o na modalidade Preg\u00e3o Eletr\u00f4nico n\u00ba 01\/2017\/CBRN, Processo n\u00ba 1.953\/2017, destinada \u00e0 contrata\u00e7\u00e3o de empresa para servi\u00e7o de limpeza, asseio e conserva\u00e7\u00e3o predial para a URAT de S\u00e3o Carlos. A abertura das propostas dar-se- \u00e1 no dia 05\/05\/2017 \u00e0s 09h00, no site www.bec.sp.gov.br, atrav\u00e9s da Oferta de Compra 260113000012017OC00002. As propostas ser\u00e3o recebidas no site a partir do dia 20\/04\/2017. Os interessados tamb\u00e9m poder\u00e3o consultar o Edital completo nos sites www.imesp.com.br (op\u00e7\u00e3o \u201cNEG\u00d3CIOS P\u00daBLICOS\u201d ou www.bec.sp.gov.br. Maiores esclarecimentos: (11) 3133-3979 ou e-mail: smalicitacoesclc@sp.gov.br.<\/p>\n<ul>\n<li><a href=\"https:\/\/smastr16.blob.core.windows.net\/editais\/2017\/04\/edital-01-2017-cbrn-limpeza-de-sao-carlos.pdf\">Download do edital<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Processo: 1.953\/2017 Pre\u00e2mbulo: Processo de contrata\u00e7\u00e3o de servi\u00e7os comuns \u2013 Contrata\u00e7\u00e3o de empresa para presta\u00e7\u00e3o de servi\u00e7os de limpeza, asseio e conserva\u00e7\u00e3o predial para a URAT de S\u00e3o Carlos. Data e hora da abertura da sess\u00e3o p\u00fablica: 05\/05\/2017 \u00e0s 09h00. Acha-se aberta na Coordenadoria de Fiscaliza\u00e7\u00e3o Ambiental, da Secretaria do Meio Ambiente, a licita\u00e7\u00e3o na [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[52,5,27],"tags":[],"_links":{"self":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/wp-json\/wp\/v2\/posts\/29075"}],"collection":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/wp-json\/wp\/v2\/comments?post=29075"}],"version-history":[{"count":1,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/wp-json\/wp\/v2\/posts\/29075\/revisions"}],"predecessor-version":[{"id":36615,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/wp-json\/wp\/v2\/posts\/29075\/revisions\/36615"}],"wp:attachment":[{"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/wp-json\/wp\/v2\/media?parent=29075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/wp-json\/wp\/v2\/categories?post=29075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infraestruturameioambiente.sp.gov.br\/editais\/wp-json\/wp\/v2\/tags?post=29075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}